{"id":735,"date":"2023-06-16T08:55:31","date_gmt":"2023-06-16T08:55:31","guid":{"rendered":"https:\/\/test.electraavellana.com\/aviso-legal\/"},"modified":"2023-10-20T06:58:45","modified_gmt":"2023-10-20T06:58:45","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/electraavellana.com\/es\/aviso-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"\n<p>De conformidad con la Ley 34\/2002, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, le informamos que esta web es titularidad de Electra Avellana Comercial, SLU, (en adelante &#8220;EL TITULAR&#8221;), con NIF B17659111 inscrita en el Registro Mercantil de Girona en el tomo 1641, folio 48, hoja GI-27.151. , domicilio en Mas Avellana, s\/n de Cornell\u00e0 del Terri (17844).<\/p>\n\n<p><strong>PROPIEDAD INTEL\u00b7 LECTUAL E INDUSTRIAL<\/strong><\/p>\n\n<p>Los contenidos de este sitio, incluyendo los textos, im\u00e1genes y dise\u00f1os gr\u00e1ficos, pertenecen a EL TITULAR, o a terceros que han autorizado su uso. EL TITULAR presenta estos contenidos con fines de informaci\u00f3n y promoci\u00f3n. EL TITULAR autoriza su utilizaci\u00f3n exclusivamente con estas finalidades. Cualquier utilizaci\u00f3n de estos dise\u00f1os, im\u00e1genes o textos deber\u00e1 citar expresamente su pertenencia a EL TITULAR, quien se reserva el derecho a iniciar las acciones legales oportunas para reparar los da\u00f1os y perjuicios causados por cualquier acto que vulnere sus derechos de propiedad intelectual o industrial.<\/p>\n\n<p><strong>EXCLUSI\u00d3N DE RESPONSABILIDAD<\/strong><\/p>\n\n<p>EL TITULAR act\u00faa con la m\u00e1xima diligencia posible para que los datos y la informaci\u00f3n que ofrece en su sitio web est\u00e9 actualizada en todo momento, si bien no garantiza ni se hace responsable de la exactitud y actualizaci\u00f3n de los contenidos del sitio web, reserv\u00e1ndose el derecho a modificar estos contenidos en cualquier momento. EL TITULAR tampoco ser\u00e1 responsable de la informaci\u00f3n que se puede obtener a trav\u00e9s de enlaces incluidos en el sitio web.<\/p>\n\n<p>Las relaciones comerciales con los clientes se regir\u00e1n por las condiciones generales que, en su caso, se establezcan por EL TITULAR en un documento espec\u00edfico al efecto, o por los pactos concretos que se puedan acordar con los clientes.<\/p>\n\n<p><strong>CONDICIONES DE USO<\/strong><\/p>\n\n<p>El uso de este sitio web implica la aceptaci\u00f3n plena de los t\u00e9rminos del presente aviso legal. Los posibles conflictos relativos a esta web se regir\u00e1n exclusivamente por el derecho del Estado Espa\u00f1ol. Toda persona usuaria de la web, independientemente de la jurisdicci\u00f3n territorial desde la que se produzca su acceso, acepta el cumplimiento y respecto de estas cl\u00e1usulas con renuncia expresa a cualquier otro fuero que pudiera corresponderle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De conformidad con la Ley 34\/2002, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, le informamos que esta web es titularidad de Electra Avellana Comercial, SLU, (en adelante &#8220;EL TITULAR&#8221;), con NIF B17659111 inscrita en el Registro Mercantil de Girona en el tomo 1641, folio 48, hoja GI-27.151. , domicilio en Mas Avellana, s\/n de Cornell\u00e0 del Terri (17844). PROPIEDAD INTEL\u00b7 LECTUAL E INDUSTRIAL Los contenidos de este sitio, incluyendo los textos, im\u00e1genes y dise\u00f1os gr\u00e1ficos, pertenecen a EL TITULAR, o a terceros que han autorizado su uso. EL TITULAR presenta estos contenidos con fines de informaci\u00f3n y promoci\u00f3n. EL TITULAR autoriza su utilizaci\u00f3n exclusivamente con estas finalidades. Cualquier utilizaci\u00f3n de estos dise\u00f1os, im\u00e1genes o textos deber\u00e1 citar expresamente su pertenencia a EL TITULAR, quien se reserva el derecho a iniciar las acciones legales oportunas para reparar los da\u00f1os y perjuicios causados por cualquier acto que vulnere sus derechos de propiedad intelectual o industrial. EXCLUSI\u00d3N DE RESPONSABILIDAD EL TITULAR act\u00faa con la m\u00e1xima diligencia posible para que los datos y la informaci\u00f3n que ofrece en su sitio web est\u00e9 actualizada en todo momento, si bien no garantiza ni se hace responsable de la exactitud y actualizaci\u00f3n de los contenidos del sitio web, reserv\u00e1ndose el derecho a modificar estos contenidos en cualquier momento. EL TITULAR tampoco ser\u00e1 responsable de la informaci\u00f3n que se puede obtener a trav\u00e9s de enlaces incluidos en el sitio web. Las relaciones comerciales con los clientes se regir\u00e1n por las condiciones generales que, en su caso, se establezcan por EL TITULAR en un documento espec\u00edfico al efecto, o por los pactos concretos que se puedan acordar con los clientes. CONDICIONES DE USO El uso de este sitio web implica la aceptaci\u00f3n plena de los t\u00e9rminos del presente aviso legal. Los posibles conflictos relativos a esta web se regir\u00e1n exclusivamente por el derecho del Estado Espa\u00f1ol. Toda persona usuaria de la web, independientemente de la jurisdicci\u00f3n territorial desde la que se produzca su acceso, acepta el cumplimiento y respecto de estas cl\u00e1usulas con renuncia expresa a cualquier otro fuero que pudiera corresponderle.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-735","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso legal - Electra Avellana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/electraavellana.com\/avis-legal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso legal - Electra Avellana\" \/>\n<meta property=\"og:description\" content=\"De conformidad con la Ley 34\/2002, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, le informamos que esta web es titularidad de Electra Avellana Comercial, SLU, (en adelante &#8220;EL TITULAR&#8221;), con NIF B17659111 inscrita en el Registro Mercantil de Girona en el tomo 1641, folio 48, hoja GI-27.151. , domicilio en Mas Avellana, s\/n de Cornell\u00e0 del Terri (17844). PROPIEDAD INTEL\u00b7 LECTUAL E INDUSTRIAL Los contenidos de este sitio, incluyendo los textos, im\u00e1genes y dise\u00f1os gr\u00e1ficos, pertenecen a EL TITULAR, o a terceros que han autorizado su uso. EL TITULAR presenta estos contenidos con fines de informaci\u00f3n y promoci\u00f3n. EL TITULAR autoriza su utilizaci\u00f3n exclusivamente con estas finalidades. Cualquier utilizaci\u00f3n de estos dise\u00f1os, im\u00e1genes o textos deber\u00e1 citar expresamente su pertenencia a EL TITULAR, quien se reserva el derecho a iniciar las acciones legales oportunas para reparar los da\u00f1os y perjuicios causados por cualquier acto que vulnere sus derechos de propiedad intelectual o industrial. EXCLUSI\u00d3N DE RESPONSABILIDAD EL TITULAR act\u00faa con la m\u00e1xima diligencia posible para que los datos y la informaci\u00f3n que ofrece en su sitio web est\u00e9 actualizada en todo momento, si bien no garantiza ni se hace responsable de la exactitud y actualizaci\u00f3n de los contenidos del sitio web, reserv\u00e1ndose el derecho a modificar estos contenidos en cualquier momento. EL TITULAR tampoco ser\u00e1 responsable de la informaci\u00f3n que se puede obtener a trav\u00e9s de enlaces incluidos en el sitio web. Las relaciones comerciales con los clientes se regir\u00e1n por las condiciones generales que, en su caso, se establezcan por EL TITULAR en un documento espec\u00edfico al efecto, o por los pactos concretos que se puedan acordar con los clientes. CONDICIONES DE USO El uso de este sitio web implica la aceptaci\u00f3n plena de los t\u00e9rminos del presente aviso legal. Los posibles conflictos relativos a esta web se regir\u00e1n exclusivamente por el derecho del Estado Espa\u00f1ol. Toda persona usuaria de la web, independientemente de la jurisdicci\u00f3n territorial desde la que se produzca su acceso, acepta el cumplimiento y respecto de estas cl\u00e1usulas con renuncia expresa a cualquier otro fuero que pudiera corresponderle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/electraavellana.com\/avis-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Electra Avellana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ElectraAvellana\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-20T06:58:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/electraavellana.com\\\/avis-legal\\\/\",\"url\":\"https:\\\/\\\/electraavellana.com\\\/avis-legal\\\/\",\"name\":\"Aviso legal - Electra Avellana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/electraavellana.com\\\/#website\"},\"datePublished\":\"2023-06-16T08:55:31+00:00\",\"dateModified\":\"2023-10-20T06:58:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/electraavellana.com\\\/avis-legal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/electraavellana.com\\\/avis-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/electraavellana.com\\\/avis-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/electraavellana.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/electraavellana.com\\\/#website\",\"url\":\"https:\\\/\\\/electraavellana.com\\\/\",\"name\":\"Electra Avellana\",\"description\":\"L&#039;el\u00e8ctrica de casa\",\"publisher\":{\"@id\":\"https:\\\/\\\/electraavellana.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/electraavellana.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/electraavellana.com\\\/#organization\",\"name\":\"Electra Avellana\",\"url\":\"https:\\\/\\\/electraavellana.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/electraavellana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/electraavellana.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/electraavellana-electrica-de-casa.png\",\"contentUrl\":\"https:\\\/\\\/electraavellana.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/electraavellana-electrica-de-casa.png\",\"width\":1334,\"height\":355,\"caption\":\"Electra Avellana\"},\"image\":{\"@id\":\"https:\\\/\\\/electraavellana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ElectraAvellana\",\"https:\\\/\\\/www.instagram.com\\\/electraavellana\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso legal - Electra Avellana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/electraavellana.com\/avis-legal\/","og_locale":"es_ES","og_type":"article","og_title":"Aviso legal - Electra Avellana","og_description":"De conformidad con la Ley 34\/2002, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, le informamos que esta web es titularidad de Electra Avellana Comercial, SLU, (en adelante &#8220;EL TITULAR&#8221;), con NIF B17659111 inscrita en el Registro Mercantil de Girona en el tomo 1641, folio 48, hoja GI-27.151. , domicilio en Mas Avellana, s\/n de Cornell\u00e0 del Terri (17844). PROPIEDAD INTEL\u00b7 LECTUAL E INDUSTRIAL Los contenidos de este sitio, incluyendo los textos, im\u00e1genes y dise\u00f1os gr\u00e1ficos, pertenecen a EL TITULAR, o a terceros que han autorizado su uso. EL TITULAR presenta estos contenidos con fines de informaci\u00f3n y promoci\u00f3n. EL TITULAR autoriza su utilizaci\u00f3n exclusivamente con estas finalidades. Cualquier utilizaci\u00f3n de estos dise\u00f1os, im\u00e1genes o textos deber\u00e1 citar expresamente su pertenencia a EL TITULAR, quien se reserva el derecho a iniciar las acciones legales oportunas para reparar los da\u00f1os y perjuicios causados por cualquier acto que vulnere sus derechos de propiedad intelectual o industrial. EXCLUSI\u00d3N DE RESPONSABILIDAD EL TITULAR act\u00faa con la m\u00e1xima diligencia posible para que los datos y la informaci\u00f3n que ofrece en su sitio web est\u00e9 actualizada en todo momento, si bien no garantiza ni se hace responsable de la exactitud y actualizaci\u00f3n de los contenidos del sitio web, reserv\u00e1ndose el derecho a modificar estos contenidos en cualquier momento. EL TITULAR tampoco ser\u00e1 responsable de la informaci\u00f3n que se puede obtener a trav\u00e9s de enlaces incluidos en el sitio web. Las relaciones comerciales con los clientes se regir\u00e1n por las condiciones generales que, en su caso, se establezcan por EL TITULAR en un documento espec\u00edfico al efecto, o por los pactos concretos que se puedan acordar con los clientes. CONDICIONES DE USO El uso de este sitio web implica la aceptaci\u00f3n plena de los t\u00e9rminos del presente aviso legal. Los posibles conflictos relativos a esta web se regir\u00e1n exclusivamente por el derecho del Estado Espa\u00f1ol. Toda persona usuaria de la web, independientemente de la jurisdicci\u00f3n territorial desde la que se produzca su acceso, acepta el cumplimiento y respecto de estas cl\u00e1usulas con renuncia expresa a cualquier otro fuero que pudiera corresponderle.","og_url":"https:\/\/electraavellana.com\/avis-legal\/","og_site_name":"Electra Avellana","article_publisher":"https:\/\/www.facebook.com\/ElectraAvellana","article_modified_time":"2023-10-20T06:58:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/electraavellana.com\/avis-legal\/","url":"https:\/\/electraavellana.com\/avis-legal\/","name":"Aviso legal - Electra Avellana","isPartOf":{"@id":"https:\/\/electraavellana.com\/#website"},"datePublished":"2023-06-16T08:55:31+00:00","dateModified":"2023-10-20T06:58:45+00:00","breadcrumb":{"@id":"https:\/\/electraavellana.com\/avis-legal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/electraavellana.com\/avis-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/electraavellana.com\/avis-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/electraavellana.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Aviso legal"}]},{"@type":"WebSite","@id":"https:\/\/electraavellana.com\/#website","url":"https:\/\/electraavellana.com\/","name":"Electra Avellana","description":"L&#039;el\u00e8ctrica de casa","publisher":{"@id":"https:\/\/electraavellana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/electraavellana.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/electraavellana.com\/#organization","name":"Electra Avellana","url":"https:\/\/electraavellana.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/electraavellana.com\/#\/schema\/logo\/image\/","url":"https:\/\/electraavellana.com\/wp-content\/uploads\/2023\/05\/electraavellana-electrica-de-casa.png","contentUrl":"https:\/\/electraavellana.com\/wp-content\/uploads\/2023\/05\/electraavellana-electrica-de-casa.png","width":1334,"height":355,"caption":"Electra Avellana"},"image":{"@id":"https:\/\/electraavellana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ElectraAvellana","https:\/\/www.instagram.com\/electraavellana\/"]}]}},"_links":{"self":[{"href":"https:\/\/electraavellana.com\/es\/wp-json\/wp\/v2\/pages\/735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/electraavellana.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/electraavellana.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/electraavellana.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/electraavellana.com\/es\/wp-json\/wp\/v2\/comments?post=735"}],"version-history":[{"count":1,"href":"https:\/\/electraavellana.com\/es\/wp-json\/wp\/v2\/pages\/735\/revisions"}],"predecessor-version":[{"id":739,"href":"https:\/\/electraavellana.com\/es\/wp-json\/wp\/v2\/pages\/735\/revisions\/739"}],"wp:attachment":[{"href":"https:\/\/electraavellana.com\/es\/wp-json\/wp\/v2\/media?parent=735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}